{"id":5878,"date":"2023-01-06T19:43:52","date_gmt":"2023-01-06T19:43:52","guid":{"rendered":"http:\/\/localhost:10024\/plataforma\/presentaciones-inteligentes\/"},"modified":"2023-03-19T23:56:15","modified_gmt":"2023-03-19T23:56:15","slug":"presentaciones-inteligentes","status":"publish","type":"page","link":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/","title":{"rendered":"presentaciones inteligentes"},"content":{"rendered":"\n<div class=\"wp-block-genesis-blocks-gb-columns gb-slate-section-hero-with-buttons gb-slate-section-hero-buttons rounded-corner-bottom-right post-2325-a gb-layout-columns-1 one-column gb-has-background-dim gb-has-background-dim-20 has-dark-green-background-color gb-columns-center alignfull\" style=\"background-position:48% 72%\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-1 gb-is-responsive-column\" style=\"max-width:1680px\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<div class=\"wp-block-genesis-blocks-gb-columns gb-layout-columns-2 gb-2-col-equal gb-columns-center alignfull\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-5 gb-is-responsive-column\" style=\"max-width:1210px\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column gb-is-vertically-aligned-top\"><div class=\"gb-block-layout-column-inner\">\n<h1 class=\"viewport-section fade-effect has-text-color wp-block-heading\" style=\"color:#f5f5f5\">presentaciones inteligentes<\/h1>\n\n\n\n<p class=\"viewport-section fade-effect has-white-color has-text-color wp-block-paragraph\">Las presentaciones inteligentes eliminan el procesamiento manual y la introducci\u00f3n de datos, liberando a las aseguradoras y a los gestores de garant\u00edas para que centren sus recursos y presupuestos en suscribir el negocio m\u00e1s rentable, con rapidez.<\/p>\n\n\n\n<div style=\"height:\" aria-hidden=\"true\" class=\"wp-block-spacer banner-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/ingestion.meaplatform.com\/login\"><strong>Pruebe los env\u00edos inteligentes<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.meaplatform.com\/contact\/\"><strong>P\u00f3ngase en contacto<\/strong><\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column gb-is-vertically-aligned-center\"><div class=\"gb-block-layout-column-inner\">\n<figure class=\"wp-block-image size-full is-resized home-banner-logo parallax-decor top-effect\"><img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"727\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png\" alt=\"\" class=\"wp-image-114\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png 579w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo-239x300.png 239w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo-300x377.png 300w\" sizes=\"auto, (max-width: 579px) 100vw, 579px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull platform-section-2 post-2325-b\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:35%\">\n<figure class=\"wp-block-image size-large solution-left-image parallax-block\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1024x683.jpg\" alt=\"\" class=\"wp-image-4198\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1536x1024.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-2048x1365.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1200x800.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Trabajo en equipo multirracial.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full green-arrow\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"128\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/down-arrow.png\" alt=\"\" class=\"wp-image-131\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:65%\">\n<div class=\"wp-block-genesis-blocks-gb-container section-2-text gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<h2 class=\"viewport-section fade-in-down wp-block-heading\" style=\"font-style:normal;font-weight:300\">para todas las aseguradoras y MGA, las presentaciones son densas e incoherentes<\/h2>\n\n\n\n<p class=\"viewport-section fade-in-down wp-block-paragraph\">Como resultado, los suscriptores pasan horas extrayendo manualmente datos de miles de p\u00e1ginas de correos electr\u00f3nicos y documentos, lo que supone una enorme merma de recursos.<\/p>\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns platform-tech-text-with-border post-2325-c gb-layout-columns-2 gb-2-col-wideleft gb-columns-center alignfull\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\" style=\"max-width:910px\">\n<div class=\"wp-block-genesis-blocks-gb-column viewport-section fade-in-up gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<h2 class=\"viewport-section fade-in-down wp-block-heading\">mea intelligent submissions extrae y prioriza autom\u00e1ticamente los riesgos para que los suscriptores tengan todo lo que necesitan para centrarse en la suscripci\u00f3n<\/h2>\n\n\n\n<p class=\"viewport-section fade-in-down wp-block-paragraph\">el usuario simplemente decide qu\u00e9 informaci\u00f3n necesita y c\u00f3mo quiere que se la presenten. ora es una IA de seguros preentrenada, por lo que funciona de inmediato en lugar de tener que pasar meses de desarrollo.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns post-2325-d gb-layout-columns-1 one-column alignfull\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<figure class=\"wp-block-image size-large platform-tech-image parallax-block\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1024x679.jpg\" alt=\"\" class=\"wp-image-4200\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1024x679.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-300x199.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-768x509.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1536x1019.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-2048x1358.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1200x796.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1400x929.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Un hombre de negocios discute con un colega durante una reuni\u00f3n de equipo en la sala de conferencias de una oficina.<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns gb-slate-section-hero-with-buttons gb-slate-section-hero-buttons about-credentials post-62-g gb-layout-columns-1 one-column gb-has-background-dim gb-has-background-dim-20 has-white-background-color alignfull\" style=\"background-position:48% 72%\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-1 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<div class=\"wp-block-columns section-3-col is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column left-column viewport-section move-margin-effect is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-white-color has-text-color wp-block-heading\">featured <span class=\"green\">benefits<\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las presentaciones inteligentes reducen los costes y devuelven un tiempo valioso a los suscriptores, lo que permite a la empresa centrarse en impulsar la ventaja competitiva.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column section-3-roll-over-links viewport-section move-margin-effect is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-genesis-blocks-gb-container gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<div class=\"wp-block-columns list-item-hover is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100px\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"43\" height=\"43\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/2-3-icon.png\" alt=\"\" class=\"wp-image-2638\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\">0.5-3%<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\"><strong>reducci\u00f3n del ratio combinado. Mejore su ratio combinado eliminando pasos manuales y aumentando el tiempo de los suscriptores para suscribir riesgos.<\/strong><\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns list-item-hover is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100px\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"54\" height=\"56\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/60-icon.png\" alt=\"\" class=\"wp-image-2639\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\">40%<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\"><strong>aumento de la capacidad de suscripci\u00f3n. La selecci\u00f3n autom\u00e1tica de riesgos permite a los suscriptores centrarse siempre en los riesgos adecuados.<\/strong><\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns list-item-hover is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100px\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"46\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/40-icon.png\" alt=\"\" class=\"wp-image-2640\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\">60% <\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\"><strong>Reducci\u00f3n de costes. Eliminaci\u00f3n de los pasos manuales en la extracci\u00f3n de la presentaci\u00f3n y el proceso de suscripci\u00f3n.<\/strong><\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns list-item-hover is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100px\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"43\" height=\"42\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/clock-icon.png.png\" alt=\"\" class=\"wp-image-2641\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">horas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.meaplatform.com\/platform\/#mga\"><strong>de implantar. la plataforma mea funciona al instante para su empresa<\/strong><\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns featured-resources gb-layout-columns-1 one-column gb-columns-center alignfull\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\" style=\"max-width:1210px\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<h2 class=\"alignfull viewport-section move-margin-effect wp-block-heading\">recursos destacados y casos pr\u00e1cticos<\/h2>\n\n\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\" data-paged=\"1\" data-attrs=\"{&quot;blockName&quot;:&quot;core\\\/query&quot;,&quot;attrs&quot;:{&quot;queryId&quot;:32,&quot;query&quot;:{&quot;perPage&quot;:3,&quot;pages&quot;:&quot;1&quot;,&quot;offset&quot;:0,&quot;postType&quot;:&quot;tapacode_document&quot;,&quot;order&quot;:&quot;desc&quot;,&quot;orderBy&quot;:&quot;date&quot;,&quot;author&quot;:&quot;&quot;,&quot;search&quot;:&quot;&quot;,&quot;exclude&quot;:[],&quot;sticky&quot;:&quot;&quot;,&quot;inherit&quot;:false,&quot;parents&quot;:[]},&quot;displayLayout&quot;:{&quot;type&quot;:&quot;flex&quot;,&quot;columns&quot;:3}},&quot;innerBlocks&quot;:[{&quot;blockName&quot;:&quot;core\\\/post-template&quot;,&quot;attrs&quot;:[],&quot;innerBlocks&quot;:[{&quot;blockName&quot;:&quot;core\\\/post-terms&quot;,&quot;attrs&quot;:{&quot;term&quot;:&quot;category&quot;},&quot;innerBlocks&quot;:[],&quot;innerHTML&quot;:&quot;&quot;,&quot;innerContent&quot;:[]},{&quot;blockName&quot;:&quot;core\\\/post-featured-image&quot;,&quot;attrs&quot;:{&quot;isLink&quot;:true,&quot;align&quot;:&quot;wide&quot;},&quot;innerBlocks&quot;:[],&quot;innerHTML&quot;:&quot;&quot;,&quot;innerContent&quot;:[]},{&quot;blockName&quot;:&quot;core\\\/html&quot;,&quot;attrs&quot;:[],&quot;innerBlocks&quot;:[],&quot;innerHTML&quot;:&quot;\\n&lt;div class=\\&quot;overlay\\&quot;&gt;&lt;\\\/div&gt;\\n&quot;,&quot;innerContent&quot;:[&quot;\\n&lt;div class=\\&quot;overlay\\&quot;&gt;&lt;\\\/div&gt;\\n&quot;]},{&quot;blockName&quot;:&quot;core\\\/post-title&quot;,&quot;attrs&quot;:{&quot;level&quot;:4,&quot;isLink&quot;:true,&quot;className&quot;:&quot;viewport-section move-margin-effect&quot;},&quot;innerBlocks&quot;:[],&quot;innerHTML&quot;:&quot;&quot;,&quot;innerContent&quot;:[]}],&quot;innerHTML&quot;:&quot;\\n\\n\\n\\n\\n\\n\\n\\n&quot;,&quot;innerContent&quot;:[&quot;\\n&quot;,null,&quot;\\n\\n&quot;,null,&quot;\\n\\n&quot;,null,&quot;\\n\\n&quot;,null,&quot;\\n&quot;]}],&quot;innerHTML&quot;:&quot;\\n&lt;div class=\\&quot;wp-block-query\\&quot;&gt;&lt;\\\/div&gt;\\n&quot;,&quot;innerContent&quot;:[&quot;\\n&lt;div class=\\&quot;wp-block-query\\&quot;&gt;&quot;,null,&quot;&lt;\\\/div&gt;\\n&quot;]}\"><ul class=\"is-flex-container columns-3 wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-5797 tapacode_document type-tapacode_document status-publish has-post-thumbnail hentry category-estudio-de-caso post with-featured-image\">\n<div class=\"taxonomy-category wp-block-post-terms\"><a href=\"https:\/\/www.meaplatform.com\/es\/category\/estudio-de-caso\/\" rel=\"tag\">Estudio de caso<\/a><\/div>\n\n<figure class=\"alignwide wp-block-post-featured-image\"><a href=\"https:\/\/www.meaplatform.com\/es\/document\/digitalizacion-de-la-tramitacion-de-solicitudes-por-parte-de-una-aseguradora-global-de-danos-y-accidentes\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"2121\" height=\"1414\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Digitalizaci\u00f3n de la tramitaci\u00f3n de solicitudes por parte de una aseguradora global de da\u00f1os y accidentes\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2.jpg 2121w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-1536x1024.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-2048x1365.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-1200x800.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-1-2-2-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 2121px) 100vw, 2121px\" \/><\/a><\/figure>\n\n\n<div class=\"overlay\"><\/div>\n\n\n<h4 class=\"viewport-section move-margin-effect wp-block-post-title\"><a href=\"https:\/\/www.meaplatform.com\/es\/document\/digitalizacion-de-la-tramitacion-de-solicitudes-por-parte-de-una-aseguradora-global-de-danos-y-accidentes\/\" target=\"_self\" >Digitalizaci\u00f3n de la tramitaci\u00f3n de solicitudes por parte de una aseguradora global de da\u00f1os y accidentes<\/a><\/h4>\n<\/li><li class=\"wp-block-post post-5804 tapacode_document type-tapacode_document status-publish has-post-thumbnail hentry category-estudio-de-caso post with-featured-image\">\n<div class=\"taxonomy-category wp-block-post-terms\"><a href=\"https:\/\/www.meaplatform.com\/es\/category\/estudio-de-caso\/\" rel=\"tag\">Estudio de caso<\/a><\/div>\n\n<figure class=\"alignwide wp-block-post-featured-image\"><a href=\"https:\/\/www.meaplatform.com\/es\/document\/grupo-internacional-de-seguros-generales-y-reaseguros\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"2119\" height=\"1414\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Grupo internacional de seguros generales y reaseguros\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2.jpg 2119w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-1536x1025.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-2048x1367.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-1200x801.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-5-2-1400x934.jpg 1400w\" sizes=\"auto, (max-width: 2119px) 100vw, 2119px\" \/><\/a><\/figure>\n\n\n<div class=\"overlay\"><\/div>\n\n\n<h4 class=\"viewport-section move-margin-effect wp-block-post-title\"><a href=\"https:\/\/www.meaplatform.com\/es\/document\/grupo-internacional-de-seguros-generales-y-reaseguros\/\" target=\"_self\" >Grupo internacional de seguros generales y reaseguros<\/a><\/h4>\n<\/li><li class=\"wp-block-post post-5758 tapacode_document type-tapacode_document status-publish has-post-thumbnail hentry category-estudio-de-caso post with-featured-image\">\n<div class=\"taxonomy-category wp-block-post-terms\"><a href=\"https:\/\/www.meaplatform.com\/es\/category\/estudio-de-caso\/\" rel=\"tag\">Estudio de caso<\/a><\/div>\n\n<figure class=\"alignwide wp-block-post-featured-image\"><a href=\"https:\/\/www.meaplatform.com\/es\/document\/los-cinco-principales-subcontratistas-mundiales-de-procesamiento-empresarial\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" width=\"2121\" height=\"1414\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Los cinco principales subcontratistas mundiales de procesamiento empresarial\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3.jpg 2121w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1536x1024.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-2048x1365.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1200x800.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-3-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 2121px) 100vw, 2121px\" \/><\/a><\/figure>\n\n\n<div class=\"overlay\"><\/div>\n\n\n<h4 class=\"viewport-section move-margin-effect wp-block-post-title\"><a href=\"https:\/\/www.meaplatform.com\/es\/document\/los-cinco-principales-subcontratistas-mundiales-de-procesamiento-empresarial\/\" target=\"_self\" >Los cinco principales subcontratistas mundiales de procesamiento empresarial<\/a><\/h4>\n<\/li><\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns section-5 gb-layout-columns-2 gb-2-col-equal alignfull\" style=\"padding-top:10px\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column gb-is-vertically-aligned-bottom\"><div class=\"gb-block-layout-column-inner\">\n<h2 class=\"mb-0 wp-block-heading\">\u00faltimas noticias<\/h2>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column gb-is-vertically-aligned-bottom\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"has-text-align-right view-all mb-0 has-dark-green-color has-text-color wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns section-6 gb-layout-columns-1 one-column alignfull\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<div class=\"wp-block-genesis-blocks-gb-columns gb-layout-columns-1 one-column\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<div class=\"mea-carousel\"><div class=\"mea-carousel-post\"><a href=\"https:\/\/www.meaplatform.com\/es\/rising-edge-se-asocia-con-mea-para-impulsar-su-plataforma-de-suscripcion-digital\/\"><div class=\"mea-post-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"232\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1.jpg\" class=\"attachment-350x375 size-350x375 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1.jpg 2126w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-300x199.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1024x679.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-768x509.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1536x1019.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-2048x1358.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1200x796.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-1-1400x929.jpg 1400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/a><div class=\"mea-post-categories\"><span class=\"mea-post-category\">Mea en las noticias<\/span><\/div><a href=\"https:\/\/www.meaplatform.com\/es\/rising-edge-se-asocia-con-mea-para-impulsar-su-plataforma-de-suscripcion-digital\/\"><div class=\"mea-post-excerpt\">Rising Edge se asocia con mea para impulsar su plataforma de suscripci\u00f3n digital<\/div><\/a><\/div><div class=\"mea-carousel-post\"><a href=\"https:\/\/www.meaplatform.com\/es\/espaguetis-de-sistema-la-paradoja-de-las-insurtech\/\"><div class=\"mea-post-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"248\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2.jpg\" class=\"attachment-350x375 size-350x375 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2.jpg 2057w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-300x212.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-1024x725.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-768x544.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-1536x1088.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-2048x1451.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-1200x850.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-2-1400x992.jpg 1400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/a><div class=\"mea-post-categories\"><\/div><a href=\"https:\/\/www.meaplatform.com\/es\/espaguetis-de-sistema-la-paradoja-de-las-insurtech\/\"><div class=\"mea-post-excerpt\">Espaguetis de sistema: La paradoja de las insurtech<\/div><\/a><\/div><div class=\"mea-carousel-post\"><a href=\"https:\/\/www.meaplatform.com\/es\/mea-contrata-a-un-nuevo-director-de-tecnologia-para-impulsar-la-eficiencia-en-el-sector-de-los-seguros\/\"><div class=\"mea-post-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"234\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-scaled.jpg\" class=\"attachment-350x375 size-350x375 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-scaled.jpg 2560w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-1536x1025.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-2048x1366.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-1200x800.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-5-1400x934.jpg 1400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/a><div class=\"mea-post-categories\"><\/div><a href=\"https:\/\/www.meaplatform.com\/es\/mea-contrata-a-un-nuevo-director-de-tecnologia-para-impulsar-la-eficiencia-en-el-sector-de-los-seguros\/\"><div class=\"mea-post-excerpt\">mea contrata a un nuevo director de tecnolog\u00eda para impulsar la eficiencia en el sector de los seguros<\/div><\/a><\/div><div class=\"mea-carousel-post\"><a href=\"https:\/\/www.meaplatform.com\/es\/ai-pre-entrenado-explicado\/\"><div class=\"mea-post-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"233\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4.jpg\" class=\"attachment-350x375 size-350x375 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4.jpg 2121w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-1536x1024.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-2048x1365.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-1200x800.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/mea-new-images-4-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/a><div class=\"mea-post-categories\"><\/div><a href=\"https:\/\/www.meaplatform.com\/es\/ai-pre-entrenado-explicado\/\"><div class=\"mea-post-excerpt\">AI- Pre-entrenado : Explicado<\/div><\/a><\/div><div class=\"mea-carousel-post\"><a href=\"https:\/\/www.meaplatform.com\/es\/ventajas-de-digitalizar-los-envios\/\"><div class=\"mea-post-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"233\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2.jpg\" class=\"attachment-350x375 size-350x375 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2.jpg 2121w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-300x200.jpg 300w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-1024x683.jpg 1024w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-768x512.jpg 768w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-1536x1024.jpg 1536w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-2048x1365.jpg 2048w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-600x400.jpg 600w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-1200x800.jpg 1200w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/02\/unnamed-2-2-2-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/a><div class=\"mea-post-categories\"><\/div><a href=\"https:\/\/www.meaplatform.com\/es\/ventajas-de-digitalizar-los-envios\/\"><div class=\"mea-post-excerpt\">Ventajas de digitalizar los env\u00edos<\/div><\/a><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns gb-slate-section-hero-with-buttons gb-slate-section-hero-buttons section-7 gb-layout-columns-1 one-column gb-has-background-dim gb-has-background-dim-20 alignfull\" style=\"background-position:48% 72%\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-1 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column section-7-inner gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column left-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full section-7-bg-logo parallax-decor top-effect\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"541\" src=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/more-transparent-logo.png\" alt=\"\" class=\"wp-image-3546\" srcset=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/more-transparent-logo.png 430w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/more-transparent-logo-238x300.png 238w, https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/more-transparent-logo-300x377.png 300w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column section-7-right-col viewport-section fade-in-up is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"font-size:4rem\">pruebe este m\u00f3dulo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">descubra c\u00f3mo puede beneficiarse de los env\u00edos inteligentes de mea.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-dark-green-color has-white-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/ingestion.meaplatform.com\/login\">Pruebe los env\u00edos inteligentes<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-black-outline is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.meaplatform.com\/platform\/\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":5751,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_block_theme_hide_title":true,"footnotes":""},"class_list":["post-5878","page","type-page","status-publish","hentry","post","without-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>presentaciones inteligentes &#8211; mea platform<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"presentaciones inteligentes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/\" \/>\n<meta property=\"og:site_name\" content=\"mea platform\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-19T23:56:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@meaplatform\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/\",\"url\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/\",\"name\":\"presentaciones inteligentes &#8211; mea platform\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meaplatform.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mea-Logo.png\",\"datePublished\":\"2023-01-06T19:43:52+00:00\",\"dateModified\":\"2023-03-19T23:56:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meaplatform.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mea-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.meaplatform.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mea-Logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plataforma\",\"item\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"presentaciones inteligentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/#website\",\"url\":\"https:\\\/\\\/www.meaplatform.com\\\/\",\"name\":\"mea platform\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/#organization\"},\"alternateName\":\"mea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meaplatform.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/#organization\",\"name\":\"mea platform\",\"alternateName\":\"mea\",\"url\":\"https:\\\/\\\/www.meaplatform.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/meaplatform\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/meaplatform\"],\"legalName\":\"mea platforms Group Limited\",\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.meaplatform.com\\\/es\\\/plataforma\\\/presentaciones-inteligentes\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.meaplatform.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mea-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.meaplatform.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/mea-logo-1.png\",\"width\":357,\"height\":174,\"caption\":\"mea platform\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"presentaciones inteligentes &#8211; mea platform","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/","og_locale":"es_ES","og_type":"article","og_title":"presentaciones inteligentes","og_url":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/","og_site_name":"mea platform","article_modified_time":"2023-03-19T23:56:15+00:00","og_image":[{"url":"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@meaplatform","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/","url":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/","name":"presentaciones inteligentes &#8211; mea platform","isPartOf":{"@id":"https:\/\/www.meaplatform.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#primaryimage"},"image":{"@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png","datePublished":"2023-01-06T19:43:52+00:00","dateModified":"2023-03-19T23:56:15+00:00","breadcrumb":{"@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#primaryimage","url":"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png","contentUrl":"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2022\/12\/Mea-Logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meaplatform.com\/es\/"},{"@type":"ListItem","position":2,"name":"Plataforma","item":"https:\/\/www.meaplatform.com\/es\/plataforma\/"},{"@type":"ListItem","position":3,"name":"presentaciones inteligentes"}]},{"@type":"WebSite","@id":"https:\/\/www.meaplatform.com\/#website","url":"https:\/\/www.meaplatform.com\/","name":"mea platform","description":"","publisher":{"@id":"https:\/\/www.meaplatform.com\/#organization"},"alternateName":"mea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meaplatform.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place"],"@id":"https:\/\/www.meaplatform.com\/#organization","name":"mea platform","alternateName":"mea","url":"https:\/\/www.meaplatform.com\/","logo":{"@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#local-main-organization-logo"},"sameAs":["https:\/\/x.com\/meaplatform","https:\/\/www.linkedin.com\/company\/meaplatform"],"legalName":"mea platforms Group Limited","telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.meaplatform.com\/es\/plataforma\/presentaciones-inteligentes\/#local-main-organization-logo","url":"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/mea-logo-1.png","contentUrl":"https:\/\/www.meaplatform.com\/wp-content\/uploads\/2023\/01\/mea-logo-1.png","width":357,"height":174,"caption":"mea platform"}]}},"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/pages\/5878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/comments?post=5878"}],"version-history":[{"count":0,"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/pages\/5878\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/pages\/5751"}],"wp:attachment":[{"href":"https:\/\/www.meaplatform.com\/es\/wp-json\/wp\/v2\/media?parent=5878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}